{"id":1117536,"date":"2025-07-31T14:17:03","date_gmt":"2025-07-31T13:17:03","guid":{"rendered":"https:\/\/myfood.eu\/hungersnot-in-der-gemueseabteilung\/"},"modified":"2025-11-25T16:05:44","modified_gmt":"2025-11-25T15:05:44","slug":"im-gemuseregal-herrscht-hungersnot","status":"publish","type":"post","link":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/","title":{"rendered":"Im Gem\u00fcseregal herrscht Hungersnot"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Wo sind die N\u00e4hrstoffe geblieben?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Obst und Gem\u00fcse sehen oft sch\u00f6ner aus als fr\u00fcher \u2013 prall, farbig, makellos. Und doch fehlt ihnen oft das Wesentliche: der N\u00e4hrwert. Immer mehr Untersuchungen zeigen, dass frische Lebensmittel \u2013 trotz Bio-Label oder Regionalit\u00e4t \u2013 immer weniger Vitamine, Mineralien und sekund\u00e4re Pflanzenstoffe enthalten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.myfood.eu\/wp-content\/uploads\/2025\/07\/nl-juillet-2.jpg\" alt=\"\" class=\"wp-image-1109378\"\/><figcaption class=\"wp-element-caption\"><em><em>Enth\u00e4lt dieses perfekte Supermarktgem\u00fcse N\u00e4hrstoffe?<\/em><\/em><\/figcaption><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Der schleichende Verlust an Vitalstoffen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Bericht von <a href=\"https:\/\/www.deutschlandfunkkultur.de\/meinung-naehrstoffverlust-unserer-lebensmittel-100.html\"><em>Deutschlandfunk Kultur<\/em><\/a> zitiert eine drastische Aussage: \u201eAls mein Opa in den 50er-Jahren eine Orange a\u00df, bekam er damit eine Vitaminbombe. Heute br\u00e4uchte ich acht Orangen, um dieselbe Menge Vitamin A aufzunehmen.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das ist kein Einzelfall. Untersuchungen belegen: In Spinat, Tomaten, Brokkoli oder Karotten ist der Gehalt an Eisen, Magnesium oder Vitamin C in den letzten Jahrzehnten um bis zu <strong>30-40 %<\/strong> zur\u00fcckgegangen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Warum werden unsere Lebensmittel &#8220;leer&#8221;?<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Hochleistungssorten und Monokultur<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.verbraucherzentrale.de\/wissen\/lebensmittel\/kennzeichnung-und-inhaltsstoffe\/sind-unsere-boeden-und-pflanzen-arm-an-naehrstoffen-17734\">Moderne Gem\u00fcsepflanzen wurden vor allem auf Aussehen<\/a>, Ertrag und Transportf\u00e4higkeit gez\u00fcchtet. Der N\u00e4hrwert spielte dabei kaum eine Rolle. Gleichzeitig ersch\u00f6pfen Monokulturen und synthetische D\u00fcngung die B\u00f6den, was die Mineralstoffaufnahme weiter senkt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">CO\u2082 und Klimawandel<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ein h\u00f6herer CO\u2082-Gehalt in der Atmosph\u00e4re f\u00f6rdert zwar das Wachstum, verringert aber paradoxerweise die Konzentration von Vitaminen und Proteinen in Pflanzen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Fr\u00fche Ernte und lange Wege<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Obst und Gem\u00fcse werden oft unreif geerntet, transportiert, gelagert und im Supermarkt ausgestellt. Dabei gehen hitze- und <a href=\"https:\/\/sportnahrung-wehle.de\/blogs\/magazin\/nahrstoffgehalt-in-modernem-obst-und-gemuse-warum-supplementierung-wichtiger-denn-je-ist\">lichtempfindliche N\u00e4hrstoffe wie Vitamin C oder Fols\u00e4ure verloren<\/a>.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size\" style=\"font-size:18px\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-text-align-center wp-element-button\" href=\"https:\/\/myfood.pro.typeform.com\/pionier-de?source=blog-article-Nutriments2025-DE\" style=\"background-color:#2ea736\" target=\"_blank\" rel=\"noreferrer noopener\">Ich starte in die Selbstversorgung<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Weniger Inhalt zum gleichen Preis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Verbraucherinnen und Verbraucher bedeutet das: Auch wenn der Preis f\u00fcr ein Kilo Tomaten gleichbleibt, bekommt man <strong>weniger Gesundheitswert<\/strong> als noch vor 20 Jahren. <a href=\"https:\/\/www.verbraucherzentrale.de\/wissen\/lebensmittel\/kennzeichnung-und-inhaltsstoffe\/sind-unsere-boeden-und-pflanzen-arm-an-naehrstoffen-17734\">Die Verbraucherzentrale<\/a> best\u00e4tigt: Zwar schwanken die N\u00e4hrstoffgehalte je nach Sorte, Standort und Saison, aber die Trends sind eindeutig.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Was tun?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mehr Vielfalt auf dem Teller<\/strong>: Verschiedene Gem\u00fcsearten und Farben bringen unterschiedliche Vitalstoffe.<\/li>\n\n\n\n<li><strong>Regional und saisonal<\/strong> kaufen, um Transportverluste zu vermeiden.<\/li>\n\n\n\n<li><strong>Tiefk\u00fchlprodukte<\/strong> nutzen: Sie werden nach der Ernte sofort schockgefrostet und enthalten oft mehr N\u00e4hrstoffe als &#8220;frische&#8221; Importware.<\/li>\n\n\n\n<li><strong>Schonend zubereiten<\/strong>: D\u00e4mpfen statt Kochen erh\u00e4lt Vitamine.<\/li>\n\n\n\n<li><strong>Selbst anbauen<\/strong>, wenn m\u00f6glich.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/myfood-61b028269c-adhzhdbbh9gpahcz.z01.azurefd.net\/blobmyfood61b028269c\/wp-content\/uploads\/2025\/07\/nl-juillet.png\" alt=\"\" class=\"wp-image-1117754\" srcset=\"\/wp-content\/uploads\/2025\/07\/nl-juillet.png 1200w, \/wp-content\/uploads\/2025\/07\/nl-juillet-300x169.png 300w, \/wp-content\/uploads\/2025\/07\/nl-juillet-1024x576.png 1024w, \/wp-content\/uploads\/2025\/07\/nl-juillet-768x432.png 768w, \/wp-content\/uploads\/2025\/07\/nl-juillet-133x75.png 133w, \/wp-content\/uploads\/2025\/07\/nl-juillet-480x270.png 480w\" sizes=\"auto, (max-width:767px) 480px, (max-width:1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\"><em>Die eigene Nahrung produzieren, um die Herkunft und die N\u00e4hrstoffe von Obst und Gem\u00fcse selbst bestimmen zu k\u00f6nnen.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00dcbernehmen Sie die Kontrolle zur\u00fcck \u2013 mit einem Myfood-Gew\u00e4chshaus<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wie w\u00e4re es, wenn Sie nicht l\u00e4nger alles hinnehmen\u2026 sondern endlich selbst anbauen?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit einem Myfood-Gew\u00e4chshaus bauen Sie Ihre eigenen Fr\u00fcchte und Gem\u00fcse das ganze Jahr \u00fcber direkt bei sich zu Hause an. Sie s\u00e4en, ernten zur richtigen Reife und entdecken den echten Geschmack wieder \u2013 eine Frische, die kein Supermarkt bieten kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schluss mit Zweifeln \u00fcber die Herkunft oder verlorene Vitamine auf dem Transportweg.<br>Sie w\u00e4hlen n\u00e4hrstoffreiche Sorten, kontrollieren Ihre Inputs und vermeiden Verluste durch Lagerung und Logistik. Bonus: Sie leisten einen echten Beitrag zum Umweltschutz. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Ergebnis? Ultrafrisches, gesundes und geschmackvolles Essen \u2013 von Ihnen selbst erzeugt.<br>Es ist konkret, erf\u00fcllend, und ver\u00e4ndert alles: f\u00fcr Ihre Gesundheit, Ihre Familie\u2026 und Ihr Vertrauen in die Zukunft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-buttons wp-embed-aspect-16-9 wp-has-aspect-ratio is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size\" style=\"font-size:18px\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-text-align-center wp-element-button\" href=\"https:\/\/myfood.pro.typeform.com\/pionier-de?source=blog-article-Nutriments2025-DE\" style=\"background-color:#2ea736\" target=\"_blank\" rel=\"noreferrer noopener\">Ich bereite mich jetzt vor<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wo sind die N\u00e4hrstoffe geblieben? Obst und Gem\u00fcse sehen oft sch\u00f6ner aus als fr\u00fcher \u2013 prall, farbig, makellos. Und doch fehlt ihnen oft das Wesentliche: der<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":1117529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[340,339],"tags":[356,358,354,353,357,355],"class_list":["post-1117536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernaehrung","category-gesundheit","tag-2025-de","tag-gesundheit","tag-landwirte-de","tag-nahrstoffe","tag-obst-und-gemuse","tag-pestizide-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Im Gem\u00fcseregal herrscht Hungersnot - myfood - Serre innovante et Permaculture<\/title>\n<meta name=\"description\" content=\"Sie glauben, sich gesund zu ern\u00e4hren\u2026 In Wirklichkeit essen Sie Obst und Gem\u00fcse, das f\u00fcrs Auge gez\u00fcchtet wurde \u2013 aber frei von N\u00e4hrstoffe ist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im Gem\u00fcseregal herrscht Hungersnot - myfood - Serre innovante et Permaculture\" \/>\n<meta property=\"og:description\" content=\"Sie glauben, sich gesund zu ern\u00e4hren\u2026 In Wirklichkeit essen Sie Obst und Gem\u00fcse, das f\u00fcrs Auge gez\u00fcchtet wurde \u2013 aber frei von N\u00e4hrstoffe ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/\" \/>\n<meta property=\"og:site_name\" content=\"myfood - Serre innovante et Permaculture\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T13:17:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T15:05:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/myfood-61b028269c-adhzhdbbh9gpahcz.z01.azurefd.net\/blobmyfood61b028269c\/wp-content\/uploads\/2025\/07\/nl-juillet-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valentine Kotowski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentine Kotowski\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/\"},\"author\":{\"name\":\"Valentine Kotowski\",\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/#\\\/schema\\\/person\\\/dc3b8dc49429f2100dcba6dee196c390\"},\"headline\":\"Im Gem\u00fcseregal herrscht Hungersnot\",\"datePublished\":\"2025-07-31T13:17:03+00:00\",\"dateModified\":\"2025-11-25T15:05:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/\"},\"wordCount\":517,\"image\":{\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/#primaryimage\"},\"thumbnailUrl\":\"\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/nl-juillet-2.jpg\",\"keywords\":[\"2025\",\"Gesundheit\",\"Landwirte\",\"N\u00e4hrstoffe\",\"Obst und Gem\u00fcse\",\"Pestizide\"],\"articleSection\":[\"Ern\u00e4hrung\",\"Gesundheit\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/\",\"url\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/\",\"name\":\"Im Gem\u00fcseregal herrscht Hungersnot - myfood - Serre innovante et Permaculture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/#primaryimage\"},\"thumbnailUrl\":\"\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/nl-juillet-2.jpg\",\"datePublished\":\"2025-07-31T13:17:03+00:00\",\"dateModified\":\"2025-11-25T15:05:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/#\\\/schema\\\/person\\\/dc3b8dc49429f2100dcba6dee196c390\"},\"description\":\"Sie glauben, sich gesund zu ern\u00e4hren\u2026 In Wirklichkeit essen Sie Obst und Gem\u00fcse, das f\u00fcrs Auge gez\u00fcchtet wurde \u2013 aber frei von N\u00e4hrstoffe ist.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/#primaryimage\",\"url\":\"\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/nl-juillet-2.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/nl-juillet-2.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/2025\\\/07\\\/im-gemuseregal-herrscht-hungersnot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/myfood.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Im Gem\u00fcseregal herrscht Hungersnot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/myfood.eu\\\/de\\\/\",\"name\":\"myfood - Serre innovante et Permaculture\",\"description\":\"Se reconnecter \u00e0 son alimentation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/myfood.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/myfood.eu\\\/de\\\/#\\\/schema\\\/person\\\/dc3b8dc49429f2100dcba6dee196c390\",\"name\":\"Valentine Kotowski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/898256cf71f2421ac5b15762e001f44d8fd1719149bbed2cf550cb589270a233?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/898256cf71f2421ac5b15762e001f44d8fd1719149bbed2cf550cb589270a233?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/898256cf71f2421ac5b15762e001f44d8fd1719149bbed2cf550cb589270a233?s=96&d=mm&r=g\",\"caption\":\"Valentine Kotowski\"},\"url\":\"https:\\\/\\\/myfood.eu\\\/de\\\/author\\\/valentine\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Im Gem\u00fcseregal herrscht Hungersnot - myfood - Serre innovante et Permaculture","description":"Sie glauben, sich gesund zu ern\u00e4hren\u2026 In Wirklichkeit essen Sie Obst und Gem\u00fcse, das f\u00fcrs Auge gez\u00fcchtet wurde \u2013 aber frei von N\u00e4hrstoffe ist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/","og_locale":"de_DE","og_type":"article","og_title":"Im Gem\u00fcseregal herrscht Hungersnot - myfood - Serre innovante et Permaculture","og_description":"Sie glauben, sich gesund zu ern\u00e4hren\u2026 In Wirklichkeit essen Sie Obst und Gem\u00fcse, das f\u00fcrs Auge gez\u00fcchtet wurde \u2013 aber frei von N\u00e4hrstoffe ist.","og_url":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/","og_site_name":"myfood - Serre innovante et Permaculture","article_published_time":"2025-07-31T13:17:03+00:00","article_modified_time":"2025-11-25T15:05:44+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/myfood-61b028269c-adhzhdbbh9gpahcz.z01.azurefd.net\/blobmyfood61b028269c\/wp-content\/uploads\/2025\/07\/nl-juillet-2.jpg","type":"image\/jpeg"}],"author":"Valentine Kotowski","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Valentine Kotowski","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/#article","isPartOf":{"@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/"},"author":{"name":"Valentine Kotowski","@id":"https:\/\/myfood.eu\/de\/#\/schema\/person\/dc3b8dc49429f2100dcba6dee196c390"},"headline":"Im Gem\u00fcseregal herrscht Hungersnot","datePublished":"2025-07-31T13:17:03+00:00","dateModified":"2025-11-25T15:05:44+00:00","mainEntityOfPage":{"@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/"},"wordCount":517,"image":{"@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2025\/07\/nl-juillet-2.jpg","keywords":["2025","Gesundheit","Landwirte","N\u00e4hrstoffe","Obst und Gem\u00fcse","Pestizide"],"articleSection":["Ern\u00e4hrung","Gesundheit"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/","url":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/","name":"Im Gem\u00fcseregal herrscht Hungersnot - myfood - Serre innovante et Permaculture","isPartOf":{"@id":"https:\/\/myfood.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/#primaryimage"},"image":{"@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2025\/07\/nl-juillet-2.jpg","datePublished":"2025-07-31T13:17:03+00:00","dateModified":"2025-11-25T15:05:44+00:00","author":{"@id":"https:\/\/myfood.eu\/de\/#\/schema\/person\/dc3b8dc49429f2100dcba6dee196c390"},"description":"Sie glauben, sich gesund zu ern\u00e4hren\u2026 In Wirklichkeit essen Sie Obst und Gem\u00fcse, das f\u00fcrs Auge gez\u00fcchtet wurde \u2013 aber frei von N\u00e4hrstoffe ist.","breadcrumb":{"@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/#primaryimage","url":"\/wp-content\/uploads\/2025\/07\/nl-juillet-2.jpg","contentUrl":"\/wp-content\/uploads\/2025\/07\/nl-juillet-2.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/myfood.eu\/de\/2025\/07\/im-gemuseregal-herrscht-hungersnot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/myfood.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Im Gem\u00fcseregal herrscht Hungersnot"}]},{"@type":"WebSite","@id":"https:\/\/myfood.eu\/de\/#website","url":"https:\/\/myfood.eu\/de\/","name":"myfood - Serre innovante et Permaculture","description":"Se reconnecter \u00e0 son alimentation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myfood.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/myfood.eu\/de\/#\/schema\/person\/dc3b8dc49429f2100dcba6dee196c390","name":"Valentine Kotowski","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/898256cf71f2421ac5b15762e001f44d8fd1719149bbed2cf550cb589270a233?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/898256cf71f2421ac5b15762e001f44d8fd1719149bbed2cf550cb589270a233?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/898256cf71f2421ac5b15762e001f44d8fd1719149bbed2cf550cb589270a233?s=96&d=mm&r=g","caption":"Valentine Kotowski"},"url":"https:\/\/myfood.eu\/de\/author\/valentine\/"}]}},"_links":{"self":[{"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/posts\/1117536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/comments?post=1117536"}],"version-history":[{"count":3,"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/posts\/1117536\/revisions"}],"predecessor-version":[{"id":1117758,"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/posts\/1117536\/revisions\/1117758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/media\/1117529"}],"wp:attachment":[{"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/media?parent=1117536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/categories?post=1117536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/myfood.eu\/de\/wp-json\/wp\/v2\/tags?post=1117536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}