{"id":262289,"date":"2022-08-16T09:19:32","date_gmt":"2022-08-16T07:19:32","guid":{"rendered":"https:\/\/www.myfood.eu\/?p=262289"},"modified":"2025-07-31T13:59:33","modified_gmt":"2025-07-31T12:59:33","slug":"5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui","status":"publish","type":"post","link":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/","title":{"rendered":"Restaurateur : 5 astuces pour vous diff\u00e9rencier et conqu\u00e9rir les clients d&#8217;aujourd&#8217;hui"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.myfood.eu\/wp-content\/uploads\/2022\/08\/20210707_141054-768x1024.jpg\" alt=\"\" class=\"wp-image-262596\" width=\"390\" height=\"520\"\/><\/figure><\/div>\n\n\n<p>Durant la crise sanitaire, les Fran\u00e7ais se sont adapt\u00e9s et ont modifi\u00e9 leurs habitudes de consommation. Le secteur de la <strong>restauration<\/strong> a \u00e9t\u00e9 particuli\u00e8rement impact\u00e9&nbsp;: les fermetures durant les diff\u00e9rents confinements ont entrain\u00e9 un report vers les services \u00e0 domicile et la restauration rapide. Ce sont essentiellement les restaurants traditionnels et ind\u00e9pendants qui ont subi au long terme la d\u00e9fection de leur client\u00e8le qui a pu entra\u00eener jusqu\u2019\u00e0 leur fermeture d\u00e9finitive<sup>1<\/sup>. Toutefois, les Fran\u00e7ais ne d\u00e9rogent pas \u00e0 leur r\u00e9putation mondiale de<strong> fins gastronomes<\/strong> puisque 90\u2009% d\u00e9clarent appr\u00e9cier la gastronomie et 50\u2009% des mill\u00e9niaux s\u2019y int\u00e9ressent<sup>2<\/sup>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Alors que recherchent aujourd\u2019hui les clients&nbsp;?<\/h2>\n\n\n\n<p>\u00c0 99\u2009% l\u2019accueil, le service et l\u2019ambiance. Ils estiment avoir le droit \u00e0 une <strong>alimentation de qualit\u00e9,<\/strong> respectueuse de leur sant\u00e9, du bien-\u00eatre animal et de l\u2019environnement en g\u00e9n\u00e9ral. De fait, ils vont privil\u00e9gier une cuisine \u00e0 base de <strong>produits de saison <\/strong>et en <strong>circuit court,<\/strong> se renseigner sur <strong>l\u2019origine des produits<\/strong> et veiller \u00e0 \u00e9viter leur gaspillage<sup>3<\/sup>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Embrasser la transition durable<\/h2>\n\n\n\n<p>La <strong>restauration durable, <\/strong>c&#8217;est d\u2019abord favoriser le <strong>local, <\/strong>les <strong>produits de saison<\/strong> et le<strong> v\u00e9g\u00e9tal.<\/strong> C\u2019est aussi trier et <strong>diminuer ses d\u00e9chets, \u00e9viter le gaspillage <\/strong>et le plastique, diminuer ses consommations en eau et en \u00e9nergie, utiliser des produits d\u2019entretien \u00e9cologiques<sup>4<\/sup>.<\/p>\n\n\n\n<p><strong>2 Fran\u00e7ais sur 3<\/strong> choisiraient en priorit\u00e9 un restaurant aux pratiques responsables et seraient pr\u00eats \u00e0 rajouter entre 1 et 3 euros \u00e0 l\u2019addition pour soutenir cette transition<sup>5<\/sup><\/p>\n\n\n\n<p>R\u00e9pondez \u00e0 leurs questions. Les clients d\u2019aujourd\u2019hui cherchent \u00e0 s\u2019impliquer et 58 % d\u2019entre eux sont sensibles \u00e0 la transparence sur la cuisine et la provenance des produits<sup>4<\/sup>.<\/p>\n\n\n\n<p>Faites-le savoir&nbsp;: Seulement 14 % des Fran\u00e7ais per\u00e7oivent le secteur de l\u2019h\u00f4tellerie-restauration comme moteur dans le d\u00e9veloppement du durable. Or, 90\u2009% des \u00e9tablissements d\u00e9clarent trier les d\u00e9chets, 88\u2009% limitent leur consommation en eau et \u00e9nergie, 95\u2009% veillent \u00e0 la <strong>tra\u00e7abilit\u00e9<\/strong> des produits, 89\u2009% ach\u00e8tent majoritairement local. Faites <strong>labelliser<\/strong> votre \u00e9tablissement, afficher votre engagement sur votre devanture, communiquer sur les r\u00e9seaux sociaux, etc<sup>5<\/sup>.<\/p>\n\n\n\n<p>Et pourquoi pas proposer un doggy bag en fin de repas dans un emballage recycl\u00e9 et recyclable.<\/p>\n\n\n\n<p>La restauration durable, c&#8217;est aussi \u00e9conomiser en misant sur les<strong> produits saisonniers<\/strong>, moins chers et en utilisant beaucoup moins d\u2019\u00e9nergie. C\u2019est aussi fid\u00e9liser son personnel en leur offrant <strong>un emploi qui a du sens<\/strong> et en les faisant participer \u00e0 la valorisation de sa carte et de l\u2019\u00e9tablissement<\/p>\n\n\n\n<p>Vos clients attendent que vous soyez au c\u0153ur de la transition alimentaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le \u00ab&nbsp;fait-maison&nbsp;\u00bb<\/h2>\n\n\n\n<p>Valoriser votre savoir-faire en mentionnant \u00e0 vos clients que les plats qu\u2019ils savourent, vous les avez- pr\u00e9par\u00e9s vous-m\u00eame. Cela vous parait \u00eatre une \u00e9vidence&nbsp;? et bien pas toujours pour vos convives qui se m\u00e9fient des plats surgel\u00e9s r\u00e9chauff\u00e9s au micro-ondes dans l\u2019arri\u00e8re-cuisine. Si vous le pouvez, pr\u00e9tendez au titre <strong>d\u2019artisan cuisinier<\/strong> qui vous permet d\u2019apposer <strong>la mention \u00ab&nbsp;fait maison&nbsp;\u00bb <\/strong>sur votre carte<sup>6<\/sup>. Les Fran\u00e7ais sont en qu\u00eate d\u2019<strong>authenticit\u00e9<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.myfood.eu\/wp-content\/uploads\/2022\/08\/446A0820-683x1024.jpg\" alt=\"\" class=\"wp-image-262615\" width=\"522\" height=\"782\"\/><figcaption class=\"wp-element-caption\"><em>Plat &#8220;fait-maison&#8221; de Yann Eber, restaurant la Ch\u00e8vrerie<\/em><\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">La transmission<\/h2>\n\n\n\n<p>Les clients aiment aussi apprendre les petits trucs des grands cuisiniers qu\u2019ils pourront r\u00e9utiliser une fois chez eux, et pourquoi pas partager au sein d\u2019un atelier gourmand, d\u2019une recette, un peu de votre talent&nbsp;?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019exp\u00e9rience sensorielle<\/h2>\n\n\n\n<p>\u00c9veillez les sens, vous le faites d\u00e9j\u00e0 au travers de vos plats&nbsp;: go\u00fbt, senteur, esth\u00e9tisme de l\u2019assiette, et vous pouvez continuer en leur ouvrant les portes de votre cuisine, de votre potager, leur faire cueillir l\u2019aromate qu\u2019ils retrouveront dans leur mets, d\u00e9couvrir une fleur comestible, s\u2019\u00e9merveiller devant un plant de shiso, etc. Vivre l\u2019exp\u00e9rience dans un lieu in\u00e9dit, le jardin un soir d\u2019\u00e9t\u00e9, la serre pour les soir\u00e9es plus fra\u00eeches, etc. Venir d\u00e9jeuner ou diner chez vous, c&#8217;est diff\u00e9rent, c\u2019est un lieu de d\u00e9gustation, de plaisir, de surprise.<\/p>\n\n\n\n<p>\u00ab&nbsp;Les clients peuvent oublier ce que vous avez dit, mais ils n\u2019oublieront jamais ce que vous leur avez fait ressentir \u00bb \u2013&nbsp;(Inconnu)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Une offre adapt\u00e9e aux diff\u00e9rents r\u00e9gimes alimentaires<\/h2>\n\n\n\n<p>25 \u00e0 30\u2009% des Fran\u00e7ais se d\u00e9clarent flexitariens.<sup>2<\/sup> Ils consomment de tout, mais en juste quantit\u00e9 et surtout en qualit\u00e9, en respectant et leur sant\u00e9 et la plan\u00e8te.<sup>7<\/sup> 14\u2009% des Fran\u00e7ais consomment au moins un aliment bio par jour et 71\u2009% par semaine.<sup>2<\/sup> Et m\u00eame si la France reste un pays o\u00f9 consommer de la viande est per\u00e7u comme un privil\u00e8ge et nutritionnellement essentiel,<sup>8<\/sup> 2,5 millions de Fran\u00e7ais sont v\u00e9gans ou v\u00e9g\u00e9tariens et 10\u2009% songent \u00e0 le devenir<sup>2<\/sup>.<\/p>\n\n\n\n<p>En tout, 42\u2009% des Fran\u00e7ais aiment se rendre dans des restaurants qui proposent une carte correspondant \u00e0 leurs go\u00fbts et \u00e0 leur r\u00e9gime alimentaire.<sup>8<\/sup> Ils sont aussi de plus en plus sensibles \u00e0 ce que se faire plaisir n\u2019est pas d\u2019impact n\u00e9gatif sur la sant\u00e9 ou le poids. Ils cherchent \u00e0 consommer \u00ab&nbsp;healthy&nbsp;\u00bb.<\/p>\n\n\n\n<p>Ils attendent de fait que la restauration r\u00e9ponde \u00e0 leur nouveau mode de consommation. Or par exemple, seulement 37\u2009% des \u00e9tablissements proposent des produits bio.<sup>2<\/sup><\/p>\n\n\n\n<p>Faites leur plaisir, proposez toujours au moins un plat v\u00e9g\u00e9tarien dans votre carte, des recettes sans gluten, du poisson et du bio. Vous vous d\u00e9marquerez ainsi facilement de la concurrence. Montrez que vous \u00eates aux petits soins pour vos clients et ainsi, vous les fid\u00e9liserez.<\/p>\n\n\n\n<p>Et dernier petit conseil, n\u2019oubliez pas que \u00ab&nbsp;La perception de votre client est votre r\u00e9alit\u00e9 \u00bb&nbsp; \u2013&nbsp;Kate Zabriskie<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.myfood.eu\/wp-content\/uploads\/2022\/08\/446A0907-1024x683.jpg\" alt=\"\" class=\"wp-image-263206\" width=\"768\" height=\"512\"\/><figcaption class=\"wp-element-caption\"><em>Yann Eber, chef cuisinier de la ch\u00e8vrerie<\/em><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-group alignfull has-text-color has-background\" style=\"color:#000000;background-color:#ffffff\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/myfood.eu\/fr\/devenir-pionnier\/professionnels\/\" style=\"border-radius:50px;color:#ffffff;background-color:#2ea736\">J&#8217;installe une serre dans mon entreprise<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Sources<\/h3>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>Manceau, S., &amp; de Narp, M. (2022, 14 f\u00e9vrier). <em>Transformation de la restauration : comment bien dig\u00e9rer les outils num\u00e9riques ?<\/em> Roland Berger. <a href=\"https:\/\/www.rolandberger.com\/fr\/Insights\/Publications\/Transformation-de-la-restauration-comment-bien-dig%C3%A9rer-les-outils-num%C3%A9riques.html \">https:\/\/www.rolandberger.com\/fr\/Insights\/Publications\/Transformation-de-la-restauration-comment-bien-dig%C3%A9rer-les-outils-num%C3%A9riques.html <\/a><\/li>\n\n\n\n<li><em>Les chiffres cl\u00e9s du secteur food en 2021\u20132022<\/em>. (s. d.). Alioze. <a href=\"https:\/\/www.alioze.com\/chiffres-food\">https:\/\/www.alioze.com\/chiffres-food<\/a><\/li>\n\n\n\n<li><em>Qu\u2019attendent les Fran\u00e7ais de leurs restaurants \u00e0 l\u2019heure de la r\u00e9ouverture ?<\/em> (s. d.). Savencia Fromage &amp; Dairy Foodservice. <a href=\"https:\/\/www.savencia-fd-foodservice.com\/actualites\/les-attentes-des-francais-a-la-reouverture-des-restaurants\/\">https:\/\/www.savencia-fd-foodservice.com\/actualites\/les-attentes-des-francais-a-la-reouverture-des-restaurants\/<\/a><\/li>\n\n\n\n<li>Metro. (s. d.). <em>Le guide pour devenir un restaurant \u00e9co-responsable<\/em>. <a href=\"https:\/\/www.metro.fr\/inspiration\/conseil-passer-durable-CHR\/guide-restaurant-eco-responsable \">https:\/\/www.metro.fr\/inspiration\/conseil-passer-durable-CHR\/guide-restaurant-eco-responsable <\/a><\/li>\n\n\n\n<li><em>\u00c9tude IFOP &#8211; Pratiques responsables dans les bars et restaurants \u2013<\/em>. (2021, 30 avril). TendanceRestauration.fr. <a href=\"https:\/\/www.tendancerestauration.fr\/communiques-de-presse\/248-etude-ifop-pratiques-responsables-dans-les-bars-et-restaurants\">https:\/\/www.tendancerestauration.fr\/communiques-de-presse\/248-etude-ifop-pratiques-responsables-dans-les-bars-et-restaurants<\/a><\/li>\n\n\n\n<li>City Presse. (2022, 11 juillet). Gastronomie : Comment la restauration valorise son savoir-faire (et son authenticit\u00e9). 20 minutes. <a href=\"https:\/\/www.20minutes.fr\/economie\/3315755-20220627-quand-la-restauration-valorise-son-savoir-faire\">https:\/\/www.20minutes.fr\/economie\/3315755-20220627-quand-la-restauration-valorise-son-savoir-faire<\/a><\/li>\n\n\n\n<li><em>Le flexitarien est l\u2019omnivore du 21e si\u00e8cle, un consommateur \u00e9clair\u00e9, qui mange de tout<\/em>. (s. d.). Naturellement Flexitariens. <a href=\"https:\/\/www.naturellement-flexitariens.fr\/fiche-pedagogique\/etre-flexitarien\/?gclid=Cj0KCQjwxIOXBhCrARIsAL1QFCZYMwNmHC-2Ycell8f85IzQ0iTqM3-8qnLF3D4IpFah2uh2CY60kWAaAi6PEALw_wcB\">https:\/\/www.naturellement-flexitariens.fr\/fiche-pedagogique\/etre-flexitarien\/?gclid=Cj0KCQjwxIOXBhCrARIsAL1QFCZYMwNmHC-2Ycell8f85IzQ0iTqM3-8qnLF3D4IpFah2uh2CY60kWAaAi6PEALw_wcB<\/a><\/li>\n\n\n\n<li>Bourelle, H. (2022, 8 f\u00e9vrier). <em>La France, ce pays qui r\u00e9siste au r\u00e9gime v\u00e9g\u00e9tarien<\/em>. Reporterre, le quotidien de l\u2019\u00e9cologie. <a href=\"https:\/\/reporterre.net\/La-France-ce-pays-qui-resiste-au-r\u00e9gime-vegetarien\">https:\/\/reporterre.net\/La-France-ce-pays-qui-resiste-au-r\u00e9gime-vegetarien<\/a><\/li>\n<\/ol>\n\n\n\n<div class=\"wp-block-group alignfull has-text-color has-background\" style=\"color:#000000;background-color:#ffffff\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-2 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/myfood.typeform.com\/to\/RiWjBz?utm_source=site&amp;utm_medium=sghpage&amp;utm_campaign=button&amp;typeform-source=1AOU22\" style=\"border-radius:50px;color:#ffffff;background-color:#2ea736\">J&#8217;installe une serre chez moi<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:64px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durant la crise sanitaire, les Fran\u00e7ais se sont adapt\u00e9s et ont modifi\u00e9 leurs habitudes de consommation. Le secteur de la restauration a \u00e9t\u00e9 particuli\u00e8rement impact\u00e9&nbsp;: les<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":263245,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[335],"tags":[80,81,82,83,84],"class_list":["post-262289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe","tag-bio","tag-circuit-court","tag-legumes-2","tag-restaurant","tag-saison"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Restaurateur : 5 astuces pour vous diff\u00e9rencier et conqu\u00e9rir les clients d&#039;aujourd&#039;hui - myfood - Serre innovante et Permaculture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurateur : 5 astuces pour vous diff\u00e9rencier et conqu\u00e9rir les clients d&#039;aujourd&#039;hui - myfood - Serre innovante et Permaculture\" \/>\n<meta property=\"og:description\" content=\"Durant la crise sanitaire, les Fran\u00e7ais se sont adapt\u00e9s et ont modifi\u00e9 leurs habitudes de consommation. Le secteur de la restauration a \u00e9t\u00e9 particuli\u00e8rement impact\u00e9&nbsp;: les [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/\" \/>\n<meta property=\"og:site_name\" content=\"myfood - Serre innovante et Permaculture\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-16T07:19:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T12:59:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/myfood.eu\/wp-content\/uploads\/2022\/08\/446A0599-scaled-e1660819956385.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1708\" \/>\n\t<meta property=\"og:image:height\" content=\"1572\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@admin@myfood.eu\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/\",\"url\":\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/\",\"name\":\"Restaurateur : 5 astuces pour vous diff\u00e9rencier et conqu\u00e9rir les clients d'aujourd'hui - myfood - Serre innovante et Permaculture\",\"isPartOf\":{\"@id\":\"https:\/\/myfood.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#primaryimage\"},\"thumbnailUrl\":\"\/wp-content\/uploads\/2022\/08\/446A0599-scaled-e1660819956385.jpg\",\"datePublished\":\"2022-08-16T07:19:32+00:00\",\"dateModified\":\"2025-07-31T12:59:33+00:00\",\"author\":{\"@id\":\"https:\/\/myfood.eu\/fr\/#\/schema\/person\/66baf1e5a9518dc0cf5050e34a6759bd\"},\"breadcrumb\":{\"@id\":\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#primaryimage\",\"url\":\"\/wp-content\/uploads\/2022\/08\/446A0599-scaled-e1660819956385.jpg\",\"contentUrl\":\"\/wp-content\/uploads\/2022\/08\/446A0599-scaled-e1660819956385.jpg\",\"width\":1708,\"height\":1572},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/myfood.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurateur : 5 astuces pour vous diff\u00e9rencier et conqu\u00e9rir les clients d&#8217;aujourd&#8217;hui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/myfood.eu\/fr\/#website\",\"url\":\"https:\/\/myfood.eu\/fr\/\",\"name\":\"myfood - Serre innovante et Permaculture\",\"description\":\"Se reconnecter \u00e0 son alimentation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/myfood.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/myfood.eu\/fr\/#\/schema\/person\/66baf1e5a9518dc0cf5050e34a6759bd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/myfood.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad33338237077d3cb1a62a1997e5bf78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad33338237077d3cb1a62a1997e5bf78?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/myfood.eu\",\"https:\/\/x.com\/admin@myfood.eu\"],\"url\":\"https:\/\/myfood.eu\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurateur : 5 astuces pour vous diff\u00e9rencier et conqu\u00e9rir les clients d'aujourd'hui - myfood - Serre innovante et Permaculture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/","og_locale":"fr_FR","og_type":"article","og_title":"Restaurateur : 5 astuces pour vous diff\u00e9rencier et conqu\u00e9rir les clients d'aujourd'hui - myfood - Serre innovante et Permaculture","og_description":"Durant la crise sanitaire, les Fran\u00e7ais se sont adapt\u00e9s et ont modifi\u00e9 leurs habitudes de consommation. Le secteur de la restauration a \u00e9t\u00e9 particuli\u00e8rement impact\u00e9&nbsp;: les [\u2026]","og_url":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/","og_site_name":"myfood - Serre innovante et Permaculture","article_published_time":"2022-08-16T07:19:32+00:00","article_modified_time":"2025-07-31T12:59:33+00:00","og_image":[{"width":1708,"height":1572,"url":"https:\/\/myfood.eu\/wp-content\/uploads\/2022\/08\/446A0599-scaled-e1660819956385.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@admin@myfood.eu","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/","url":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/","name":"Restaurateur : 5 astuces pour vous diff\u00e9rencier et conqu\u00e9rir les clients d'aujourd'hui - myfood - Serre innovante et Permaculture","isPartOf":{"@id":"https:\/\/myfood.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#primaryimage"},"image":{"@id":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2022\/08\/446A0599-scaled-e1660819956385.jpg","datePublished":"2022-08-16T07:19:32+00:00","dateModified":"2025-07-31T12:59:33+00:00","author":{"@id":"https:\/\/myfood.eu\/fr\/#\/schema\/person\/66baf1e5a9518dc0cf5050e34a6759bd"},"breadcrumb":{"@id":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#primaryimage","url":"\/wp-content\/uploads\/2022\/08\/446A0599-scaled-e1660819956385.jpg","contentUrl":"\/wp-content\/uploads\/2022\/08\/446A0599-scaled-e1660819956385.jpg","width":1708,"height":1572},{"@type":"BreadcrumbList","@id":"https:\/\/myfood.eu\/fr\/2022\/08\/5-astuces-pour-vous-differencier-et-conquerir-les-clients-daujourdhui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/myfood.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Restaurateur : 5 astuces pour vous diff\u00e9rencier et conqu\u00e9rir les clients d&#8217;aujourd&#8217;hui"}]},{"@type":"WebSite","@id":"https:\/\/myfood.eu\/fr\/#website","url":"https:\/\/myfood.eu\/fr\/","name":"myfood - Serre innovante et Permaculture","description":"Se reconnecter \u00e0 son alimentation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myfood.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/myfood.eu\/fr\/#\/schema\/person\/66baf1e5a9518dc0cf5050e34a6759bd","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/myfood.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ad33338237077d3cb1a62a1997e5bf78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad33338237077d3cb1a62a1997e5bf78?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/myfood.eu","https:\/\/x.com\/admin@myfood.eu"],"url":"https:\/\/myfood.eu\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/posts\/262289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/comments?post=262289"}],"version-history":[{"count":1,"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/posts\/262289\/revisions"}],"predecessor-version":[{"id":1117521,"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/posts\/262289\/revisions\/1117521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/media\/263245"}],"wp:attachment":[{"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/media?parent=262289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/categories?post=262289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/myfood.eu\/fr\/wp-json\/wp\/v2\/tags?post=262289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}